{"id":88,"date":"2023-04-16T11:44:47","date_gmt":"2023-04-16T14:44:47","guid":{"rendered":"https:\/\/demosites.royal-elementor-addons.com\/personal-blog-v3\/?p=88"},"modified":"2023-09-03T20:41:43","modified_gmt":"2023-09-03T23:41:43","slug":"historico-do-evento","status":"publish","type":"post","link":"https:\/\/erelin.vaelp-tl.com\/index.php\/2023\/04\/16\/historico-do-evento\/","title":{"rendered":"HIST\u00d3RICO DO EVENTO"},"content":{"rendered":"<p><span style=\"font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O Encontro Regional de Lingu\u00edstica \u2013 ERELIN, evento de car\u00e1ter Regional e Itinerante, teve sua origem na Universidade Estadual de Alagoas, Campus IV \u2013 S\u00e3o Miguel dos Campos, em 2013, com o intuito de promover a inser\u00e7\u00e3o do curso de Letras da UNEAL \u2013 Campus IV \u2013 nas discuss\u00f5es mais recentes dos Estudos Lingu\u00edsticos.<\/span><\/p>\r\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Em sua segunda edi\u00e7\u00e3o, realizada em 2016, na Universidade Estadual de Alagoas, Campus III \u2013 Palmeira dos \u00cdndios, o II ERELIN foi desenvolvido sob a tem\u00e1tica \u201cL\u00ednguas: usos e gram\u00e1ticas\u201d, proporcionando aos discentes participantes uma imers\u00e3o nas diversas correntes te\u00f3ricas e metodol\u00f3gicas de investiga\u00e7\u00e3o cient\u00edfica na \u00e1rea de lingu\u00edstica. O evento contou com a participa\u00e7\u00e3o de 250 alunos, que contribu\u00edram para enriquecer as discuss\u00f5es e a troca de conhecimentos.<\/span><\/p>\r\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O sucesso das duas primeiras edi\u00e7\u00f5es do ERELIN impulsionou a realiza\u00e7\u00e3o do III Encontro Regional de Lingu\u00edstica, que foi realizado no per\u00edodo de 28 a 30 de novembro, na Universidade de Pernambuco \u2013 Campus Garanhuns, organizado pelo Grupo de Estudos em An\u00e1lise e Descri\u00e7\u00e3o Lingu\u00edstica \u2013 GEADLin (CNPq\/UPE). O tema escolhido para este terceiro encontro foi &#8220;Os m\u00faltiplos olhares das Teorias Lingu\u00edsticas na Contemporaneidade&#8221;. O evento atraiu a participa\u00e7\u00e3o de 750 inscritos oriundos de outros estados e tamb\u00e9m da regi\u00e3o que compreende os estados de Alagoas e Pernambuco.<\/span><\/p>\r\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O IV ERELIN ocorreu na Universidade Estadual de Alagoas &#8211; UNEAL\/ Campus Uni\u00e3o dos Palmares, no per\u00edodo de 12 a 15 de outubro de 2019, sob a tem\u00e1tica: &#8220;A Lingu\u00edstica de ontem e a de hoje: novos olhares&#8221;. Neste quarto encontro, o evento contou com a participa\u00e7\u00e3o de 180 estudantes de Letras, profissionais da educa\u00e7\u00e3o e interessados na tem\u00e1tica, refor\u00e7ando o compromisso do congresso em envolver diversos p\u00fablicos interessados no estudo da Lingu\u00edstica e suas diversas abordagens.<\/span><\/p>\r\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A continuidade e o crescimento do ERELIN ao longo dos anos t\u00eam demonstrado sua relev\u00e2ncia como espa\u00e7o de discuss\u00e3o acad\u00eamica e promo\u00e7\u00e3o do conhecimento na \u00e1rea de Lingu\u00edstica. As modalidades de participa\u00e7\u00e3o, que incluem ouvintes, apresentadores de comunica\u00e7\u00e3o oral e apresentadores de p\u00f4ster, t\u00eam possibilitado a participa\u00e7\u00e3o ativa de pesquisadores, estudantes e interessados na \u00e1rea, consolidando o evento como um espa\u00e7o de troca de experi\u00eancias e est\u00edmulo \u00e0 pesquisa lingu\u00edstica.<\/span><\/p>\r\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Com o intuito de promover um espa\u00e7o ainda mais abrangente e enriquecedor para o debate e a dissemina\u00e7\u00e3o do conhecimento na \u00e1rea de Lingu\u00edstica, o V Encontro Regional de Lingu\u00edstica \u2013 ERELIN 2023 foi planejado com o tema: &#8220;Lingu\u00edstica, pesquisa e ensino: diversidades te\u00f3ricas e suas aplica\u00e7\u00f5es&#8221;. Esse tema busca explorar as diversas vertentes te\u00f3ricas existentes na Lingu\u00edstica, bem como sua aplicabilidade no campo da pesquisa e do ensino, proporcionando um ambiente prop\u00edcio para o di\u00e1logo entre pesquisadores, estudantes e profissionais da \u00e1rea. As inscri\u00e7\u00f5es para o V Encontro Regional de Lingu\u00edstica est\u00e3o abertas e podem ser feitas <a href=\"https:\/\/erelin.vaelp-tl.com\/index.php\/pagina-de-inscricao\/\">aqui<\/a>. O congresso ser\u00e1 realizado de forma presencial na Universidade de Pernambuco, campus Garanhuns, de 11 a 14 de dezembro de 2023, e espera-se que, mais uma vez, seja um marco de conhecimento e colabora\u00e7\u00e3o para a \u00e1rea de Estudos Lingu\u00edsticos, com a presen\u00e7a de renomados palestrantes, mesas-redondas e uma variedade de atividades que enriquecer\u00e3o ainda mais o campo da Lingu\u00edstica.<\/span><\/p>\r\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>O Encontro Regional de Lingu\u00edstica \u2013 ERELIN, evento de car\u00e1ter Regional e Itinerante, teve sua origem na Universidade Estadual de Alagoas, Campus IV \u2013 S\u00e3o Miguel dos Campos, em 2013, com o intuito de promover a inser\u00e7\u00e3o do curso de Letras da UNEAL \u2013 Campus IV \u2013 nas discuss\u00f5es mais recentes dos Estudos Lingu\u00edsticos. Em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/posts\/88"}],"collection":[{"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":5,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/posts\/88\/revisions"}],"predecessor-version":[{"id":1103,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/posts\/88\/revisions\/1103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/media\/970"}],"wp:attachment":[{"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/media?parent=88"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/categories?post=88"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erelin.vaelp-tl.com\/index.php\/wp-json\/wp\/v2\/tags?post=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}